{"id":5276,"date":"2026-05-12T15:19:35","date_gmt":"2026-05-12T13:19:35","guid":{"rendered":"https:\/\/www.stadefrancais.com\/sections\/tennis\/?p=5276"},"modified":"2026-05-12T15:19:36","modified_gmt":"2026-05-12T13:19:36","slug":"week-end-argentin-au-club-sport-convivialite-et-engagement","status":"publish","type":"post","link":"https:\/\/www.stadefrancais.com\/sections\/tennis\/2026\/05\/12\/week-end-argentin-au-club-sport-convivialite-et-engagement\/","title":{"rendered":"Week-end argentin au club : sport, convivialit\u00e9 et engagement"},"content":{"rendered":"\n<p>Les 23, 24 et 25 mai prochains, le club vivra un week-end exceptionnel aux couleurs de l\u2019Argentine ! Nous aurons le plaisir d\u2019accueillir une d\u00e9l\u00e9gation de 24 joueuses du Club de Veteranas de Buenos Aires, venues partager trois jours de tennis, de rencontres et de convivialit\u00e9 dans une ambiance chaleureuse et festive.<\/p>\n\n\n\n<p>\u00c0 cette occasion, elles s\u2019affronteront en double avec 24 joueuses fran\u00e7aises, majoritairement stadistes, ainsi que quelques participantes de clubs parisiens invit\u00e9s. Cette rencontre se veut avant tout amicale et conviviale, tout en proposant un tr\u00e8s beau niveau de jeu, avec des participantes class\u00e9es entre 0 et 15\/5.<\/p>\n\n\n\n<p>Au-del\u00e0 du sport, ce week-end sera \u00e9galement plac\u00e9 sous le signe de l\u2019engagement et de la sensibilisation. Notre partenaire EndoFrance sera pr\u00e9sent tout au long de l\u2019\u00e9v\u00e9nement avec un stand d\u2019information d\u00e9di\u00e9 \u00e0 l\u2019endom\u00e9triose, afin de mieux faire conna\u00eetre cette maladie qui touche de nombreuses femmes. Une conf\u00e9rence de sensibilisation sera \u00e9galement organis\u00e9e pendant ces trois jours pour informer, \u00e9changer et r\u00e9pondre aux questions.<\/p>\n\n\n\n<p>Pour prolonger cette immersion argentine, le club organisera \u00e9galement une grande&nbsp;<strong>Soir\u00e9e Argentine \u2013 Tango &amp; Asado<\/strong>&nbsp;le dimanche 24 mai \u00e0 partir de 19h \u00e0 La Faisanderie, avec le soutien de l\u2019Ambassade d\u2019Argentine en France. Cette soir\u00e9e festive mettra \u00e0 l\u2019honneur les grandes traditions argentines autour d\u2019un moment de partage et de convivialit\u00e9.<\/p>\n\n\n\n<p>Au programme :&nbsp;<strong>asado argentin<\/strong>, vins, musique et tango live dans une atmosph\u00e8re chaleureuse et authentique. Une belle occasion pour les membres du club, les joueuses, leurs familles et leurs amis de se retrouver apr\u00e8s les rencontres sportives et de c\u00e9l\u00e9brer ensemble l\u2019esprit franco-argentin de ce week-end unique.<\/p>\n\n\n\n<p>\ud83d\udccd&nbsp;<strong>Lieu de la soir\u00e9e :<\/strong>&nbsp;La Faisanderie \u2013 All\u00e9e de Chamillard, 92430 Marnes-la-Coquette<br>\ud83d\udd56&nbsp;<strong>Horaire :<\/strong>&nbsp;Dimanche 24 mai \u00e0 partir de 19h<br>\ud83d\udcb6&nbsp;<strong>Tarifs :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>32 \u20ac par personne (asado + 1 boisson alcoolis\u00e9e)<\/li>\n\n\n\n<li>20 \u20ac par enfant (asado + 1 soft)<\/li>\n<\/ul>\n\n\n\n<p>Entre tennis, partage, culture et engagement solidaire, ce Week-end argentin promet d\u2019\u00eatre un moment fort de la vie du club.<\/p>\n\n\n\n<p>Nous esp\u00e9rons vous voir nombreux pour encourager les joueuses, d\u00e9couvrir cette belle initiative et partager ce moment convivial avec nous !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les 23, 24 et 25 mai prochains, le club vivra un week-end exceptionnel aux couleurs de l\u2019Argentine ! Nous aurons le plaisir d\u2019accueillir une d\u00e9l\u00e9gation de 24 joueuses du Club de Veteranas de Buenos Aires, venues partager trois jours de tennis, de rencontres et de convivialit\u00e9 dans une ambiance chaleureuse et festive. \u00c0 cette occasion, [&hellip;]<\/p>\n","protected":false},"author":112,"featured_media":5278,"comment_status":"closed","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"none","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[3],"tags":[],"class_list":["post-5276","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.stadefrancais.com\/sections\/tennis\/wp-json\/wp\/v2\/posts\/5276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stadefrancais.com\/sections\/tennis\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.stadefrancais.com\/sections\/tennis\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.stadefrancais.com\/sections\/tennis\/wp-json\/wp\/v2\/users\/112"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stadefrancais.com\/sections\/tennis\/wp-json\/wp\/v2\/comments?post=5276"}],"version-history":[{"count":1,"href":"https:\/\/www.stadefrancais.com\/sections\/tennis\/wp-json\/wp\/v2\/posts\/5276\/revisions"}],"predecessor-version":[{"id":5279,"href":"https:\/\/www.stadefrancais.com\/sections\/tennis\/wp-json\/wp\/v2\/posts\/5276\/revisions\/5279"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.stadefrancais.com\/sections\/tennis\/wp-json\/wp\/v2\/media\/5278"}],"wp:attachment":[{"href":"https:\/\/www.stadefrancais.com\/sections\/tennis\/wp-json\/wp\/v2\/media?parent=5276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stadefrancais.com\/sections\/tennis\/wp-json\/wp\/v2\/categories?post=5276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stadefrancais.com\/sections\/tennis\/wp-json\/wp\/v2\/tags?post=5276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}